{"id":16924,"date":"2015-12-14T16:27:07","date_gmt":"2015-12-14T15:27:07","guid":{"rendered":"https:\/\/auren.com\/ar\/new\/auren-en-la-vision-de-los-lideres-2016\/"},"modified":"2015-12-14T16:27:07","modified_gmt":"2015-12-14T15:27:07","slug":"auren-en-la-vision-de-los-lideres-2016","status":"publish","type":"new","link":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/noticias\/auren-en-la-vision-de-los-lideres-2016\/","title":{"rendered":"Auren en La Visi\u00f3n de los L\u00edderes 2016"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.auren.com\/uploads\/images\/originals\/1601.jpg\"><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p> M\u00e1s de 500 CEOs y Presidentes de las empresas top de la Argentina anticipan lo que viene. Por Fernando Tezanos Pinto, Presidente de Auren.<\/p>\n","protected":false},"featured_media":16925,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-16924","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/new\/16924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/new\/16924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/media\/16925"}],"wp:attachment":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/media?parent=16924"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/ar\/wp-json\/wp\/v2\/new-category?post=16924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}