{"id":9738,"date":"2021-02-03T10:53:16","date_gmt":"2021-02-03T09:53:16","guid":{"rendered":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/blog\/beneficios-tributarios-para-incentivar-el-sector-cultural-y-el-emprendimiento\/"},"modified":"2021-02-03T10:53:16","modified_gmt":"2021-02-03T09:53:16","slug":"beneficios-tributarios-para-incentivar-el-sector-cultural-y-el-emprendimiento","status":"publish","type":"blog","link":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/blog\/beneficios-tributarios-para-incentivar-el-sector-cultural-y-el-emprendimiento\/","title":{"rendered":"Beneficios Tributarios para incentivar el sector cultural y el emprendimiento."},"content":{"rendered":"<p>Teniendo en cuenta la emergencia econ\u00f3mica y sanitaria COVID-19, el Gobierno expidi\u00f3 en el a\u00f1o 2020 decretos ley que implican un alivio econ\u00f3mico tanto para las empresas como para los particulares. En concreto, se expidieron la Ley 2069 de 2020 y 2070 de 2020 cuyos aspectos m\u00e1s relevantes son los siguientes:<\/p>\n<p>Ley 2069 de 2020:<\/p>\n<ul>\n<li>El art. 28 de la presente ley adicion\u00f3 un par\u00e1grafo transitorio al art. 850 del Estatuto Tributario que expone que los saldos a favor en el IVA por la venta de bienes exentos de manera transitoria en aplicaci\u00f3n de los decretos legislativos 438 y 551 de 2020 podr\u00e1n ser solicitados en devoluci\u00f3n y\/o compensaci\u00f3n en proporci\u00f3n a los bienes vendidos hasta el termino de la pandemia.<\/li>\n<\/ul>\n<ul>\n<li>Se otorg\u00f3 exenci\u00f3n transitoria del IVA en la importaci\u00f3n y venta de insumos m\u00e9dicos necesarios para atender la crisis.<\/li>\n<\/ul>\n<ul>\n<li>En lo relacionado con los paneles solares, se eliminan estos del listado del art. 424 del ET en el que se detallan los bienes excluidos del IVA.<\/li>\n<\/ul>\n<ul>\n<li>Con el fin de indicar que las deducciones y descuentos por donaciones e inversiones en investigaci\u00f3n, desarrollo tecnol\u00f3gico e innovaci\u00f3n tambi\u00e9n ser\u00e1n aplicables a las donaciones a iNNpulsa realizadas por los contribuyentes del impuesto sobre la renta. No obstante, este incentivo tributario solo ser\u00e1 aplicable una vez se haya verificado el valor de la donaci\u00f3n y la aprobaci\u00f3n por parte del Ministerio de Comercio.<\/li>\n<\/ul>\n<p><strong>Ley 2070 de 2020:<\/strong><\/p>\n<ul>\n<li>Es una nueva tarifa de retenci\u00f3n en la fuente para actividades del sector cultural y de econom\u00eda naranja.<\/li>\n<li>Se fija en 4% la tarifa de retenci\u00f3n en la fuente a titulo de <em>renta sobre los pagos<\/em>&nbsp;o abonos en cuenta por conceptos de honorarios, comisiones y prestaciones de servicios correspondientes&nbsp;a 27 actividades relacionados con el sector cultural y de econom\u00eda naranja, tales como:<\/li>\n<li>Producci\u00f3n de copias a partir de grabaciones originales.<\/li>\n<li>Fabricaci\u00f3n de instrumentos musicales.<\/li>\n<li>Edici\u00f3n de libros.<\/li>\n<li>Edici\u00f3n de peri\u00f3dicos, revistas y publicaciones peri\u00f3dicas.<\/li>\n<li>Actividades de producci\u00f3n de pel\u00edculas cinematogr\u00e1ficas, videos, programas, anuncios y comerciales de televisi\u00f3n.<\/li>\n<li>Actividades de exhibici\u00f3n de pel\u00edculas cinematogr\u00e1ficas y videos.<\/li>\n<li>Actividades de grabaci\u00f3n de sonido y edici\u00f3n de m\u00fasica.<\/li>\n<li>Publicidad.<\/li>\n<li>Actividades de fotograf\u00eda.<\/li>\n<li>Creaci\u00f3n teatral.<\/li>\n<li>Artes pl\u00e1sticas y visuales.<\/li>\n<li>Actividades de espect\u00e1culos en vivo.<\/li>\n<li>Actividades de bibliotecas y archivos.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/auren.com\/co\/blog\">Blog: Auren Colombia<\/a><\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Fuente<\/p>\n<p><cite><a href=\"https:\/\/dapre.presidencia.gov.co\/normativa\/normativa\/LEY%202069%20DEL%2031%20DE%20DICIEMBRE%20DE%202020.pdf\">Ley 2069 de 2020 y Ley 270 de 2020.<\/a><\/cite><\/p><\/blockquote>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teniendo en cuenta la emergencia econ\u00f3mica y sanitaria COVID-19, el Gobierno expidi\u00f3 en el a\u00f1o 2020 decretos ley que implican un alivio econ\u00f3mico tanto para las empresas como para los [&hellip;]<\/p>\n","protected":false},"featured_media":9739,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-9738","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/blog\/9738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/blog\/9738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/media\/9739"}],"wp:attachment":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/media?parent=9738"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/co\/wp-json\/wp\/v2\/blog-category?post=9738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}