{"id":11840,"date":"2011-11-25T18:26:24","date_gmt":"2011-11-25T17:26:24","guid":{"rendered":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/new\/45-fin-del-ficto-en-la-venta-de-campos-de-eso-no-se-habla\/"},"modified":"2011-11-25T18:26:24","modified_gmt":"2011-11-25T17:26:24","slug":"45-fin-del-ficto-en-la-venta-de-campos-de-eso-no-se-habla","status":"publish","type":"new","link":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/noticias\/45-fin-del-ficto-en-la-venta-de-campos-de-eso-no-se-habla\/","title":{"rendered":"45- FIN DEL FICTO EN LA VENTA DE CAMPOS: DE ESO NO SE HABLA"},"content":{"rendered":"<p class=\"has-text-align-justify\">La C\u00e1mara de Diputados dio media sanci\u00f3n a la creaci\u00f3n del <strong>ICIR<\/strong> (Impuesto a la Concentraci\u00f3n de Inmuebles Rurales) que grava la tenencia de tierra por encima de las 2.000 h\u00e1s. CONEAT 100; 1 h\u00e1. por encima de este piso y las 2001 quedar\u00e1n alcanzadas (ver esta misma p\u00e1gina del 26\/8\/2011).<\/p>\n<p class=\"has-text-align-justify\">Pero este proyecto est\u00e1 dividido en dos. Por un lado est\u00e1 el ICIR, al que se ha dado amplia difusi\u00f3n. Pero contiene otra disposici\u00f3n que resulta tanto o m\u00e1s perniciosa que la anterior, pero a la que se ha prestado, incre\u00edblemente, much\u00edsima menos atenci\u00f3n y es la que tiene que ver con la <strong><u>eliminaci\u00f3n de la posibilidad de optar por un ficto en el caso de enajenaci\u00f3n de inmuebles rurales adquiridos antes del 30\/6\/2007<\/u><\/strong>.<\/p>\n<p class=\"has-text-align-justify\">Antes de la Reforma Tributaria la venta de campos no estaba alcanzada con impuesto a la renta, fuera el due\u00f1o persona f\u00edsica o sociedad (tampoco lo estaba la venta de inmuebles urbanos por personas, no exist\u00eda el IRPF). La introducci\u00f3n de un gravamen a la venta de tierra trajo consigo la necesidad de un atenuante: el ficto. Es as\u00ed que en la venta que realiza una sociedad se puede optar por un ficto del 6% del precio de venta sobre el que aplicar la al\u00edcuota del IRAE (25%), lo que da un <strong>1,5%<\/strong> (sobre este mismo 6% hay que aplicar el 7% a la distribuci\u00f3n de dividendos: 7% x 6% = 0,42%, por lo que tenemos en definitiva un <strong>1,92%<\/strong> del precio de venta). Si quien vende es una PF entonces el ficto es el 15% al que se le aplica el 12% de IRPF arribando a un <strong>1,8%<\/strong> del precio de venta.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>\u00bfQu\u00e9 cambia?<\/strong><\/p>\n<p class=\"has-text-align-justify\">Se permite optar por el ficto que vimos pero hasta el \u201cvalor en plaza\u201d al 30\/06\/2007. El valor en plaza al 30\/6\/2007 se determina \u201cllevando para atr\u00e1s\u201d el valor de la transacci\u00f3n usando el \u201c<em>\u00cdndice Medio del Incremento de los Precios de Venta de los Inmuebles Rurales<\/em>\u201d. A partir de ese valor (ajustado por IPC o IPPN seg\u00fan corresponda) y hasta el precio de venta, se aplicar\u00e1 la tasa correspondiente (25% \u00f3 12%) sobre la totalidad del incremento de precio.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>\u00bfQu\u00e9 hacer?<\/strong><\/p>\n<p class=\"has-text-align-justify\">Actuar. Y pronto.<\/p>\n<p class=\"has-text-align-justify\">Por suerte lo que aprob\u00f3 diputados contiene una disposici\u00f3n que dice que esto afecta a las <strong><u>ventas realizadas luego del 1\/1\/2012<\/u><\/strong>, por lo que hasta fin de a\u00f1o hay tiempo para hacer \u201calgo\u201d.<\/p>\n<p class=\"has-text-align-justify\">Lo que hay que hacer es una \u201c<strong><em>transacci\u00f3n<\/em><\/strong>\u201d en la que se actualice el valor, aprovechando la \u00faltima oportunidad de utilizar el ficto.<\/p>\n<p class=\"has-text-align-justify\">El inmueble puede estar hoy en cabeza de PF o de una sociedad. Si est\u00e1 en una sociedad, entonces puede pasarse a otra (con la precauci\u00f3n de que socios y directores sean diferentes) o a una PF. Pero si est\u00e1 en PF, no es posible \u201cpasarlo\u201d a una sociedad por el tema de la regla candado (cuando venda la sociedad, s\u00f3lo podr\u00e1 deducir el 48% del costo; es peor el remedio que la enfermedad).<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>Colonizaci\u00f3n<\/strong><\/p>\n<p class=\"has-text-align-justify\">Ahora bien, hay que tener muy en cuenta que todos los campos por encima de 500 h\u00e1s. CONEAT 100 deben ser ofrecidos a Colonizaci\u00f3n quien tiene el \u201cfirst refusal\u201d.<\/p>\n<p class=\"has-text-align-justify\">De modo que el poner un precio elevado (presumiblemente algo superior al valor de mercado actual) tiene un doble prop\u00f3sito en realidad. Por un lado desincentivar a Colonizaci\u00f3n. Por otro, actualizar el costo del campo ahora aprovechando la \u00faltima oportunidad que tenemos para liquidar por ficto, evitando (o disminuyendo) pagar impuesto en el d\u00eda de ma\u00f1ana cuando efectivamente se venda.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>Costos<\/strong><\/p>\n<p class=\"has-text-align-justify\">Evitar males mayores en el futuro puede salir hoy una fortuna. En efecto, al propio impuesto a la renta hay que agregar los costos y gastos propios de una operaci\u00f3n de este tipo (ITP -2% y 2%-, Honorarios Notariales, etc.).<\/p>\n<p class=\"has-text-align-justify\">Hay que hacer las cuentas de cu\u00e1nto es la \u201cinversi\u00f3n\u201d ahora y cuantificar el \u201cretorno\u201d despu\u00e9s (en t\u00e9rminos de ahorro de impuesto a la renta en el futuro cuando se venda realmente).<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>Colof\u00f3n<\/strong><\/p>\n<p class=\"has-text-align-justify\">Formalmente no es una norma retroactiva, pero sin dudas que constituye un cambio demasiado importante en las reglas de juego como para no alterar el humor del inversor.<\/p>\n<p class=\"has-text-align-justify\">Cuesta creer lo poco que se ha hablado del tema. Nosotros pensamos que los que tienen tierra comprada antes del 30\/6\/2007 o bien no se han enterado, o bien piensan que no vender\u00e1n nunca (ellos, pero\u2026 \u00bfy sus hijos?).<\/p>\n<p class=\"has-text-align-justify\">Un inversor ante todo esto de tener que hacer una transacci\u00f3n ahora, a las apuradas, exclam\u00f3: \u201c<em>tal vez debamos vender, vender realmente, m\u00e1s si se tiene en cuenta que las cosas se seguir\u00e1n complicando como se han venido complicando hasta ahora<\/em>\u201d.<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Diputados dio media sanci\u00f3n a la creaci\u00f3n del ICIR (Impuesto a la Concentraci\u00f3n de Inmuebles Rurales) que grava la tenencia de tierra por encima de las 2.000 [&hellip;]<\/p>\n","protected":false},"featured_media":11841,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-11840","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/new\/11840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/new\/11840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/media\/11841"}],"wp:attachment":[{"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/media?parent=11840"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/aurenweb-stg.servidortemporal.net\/uy\/wp-json\/wp\/v2\/new-category?post=11840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}